{"id":53,"count":1,"description":"","link":"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/","name":"Klinikmanagement","slug":"klinikmanagement","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Klinikmanagement Archives - Contract Cost Care Ltd.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klinikmanagement Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/\" \/>\n<meta property=\"og:site_name\" content=\"Contract Cost Care Ltd.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costcare.cc\\\/de\\\/tag\\\/klinikmanagement\\\/\",\"url\":\"https:\\\/\\\/costcare.cc\\\/de\\\/tag\\\/klinikmanagement\\\/\",\"name\":\"Klinikmanagement Archives - Contract Cost Care Ltd.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costcare.cc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costcare.cc\\\/de\\\/tag\\\/klinikmanagement\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costcare.cc\\\/de\\\/tag\\\/klinikmanagement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costcare.cc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Klinikmanagement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costcare.cc\\\/#website\",\"url\":\"https:\\\/\\\/costcare.cc\\\/\",\"name\":\"Contract Care\",\"description\":\"maximum efficiency and cost saving for your medical treatment systems\",\"publisher\":{\"@id\":\"https:\\\/\\\/costcare.cc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costcare.cc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costcare.cc\\\/#organization\",\"name\":\"Contract Care\",\"url\":\"https:\\\/\\\/costcare.cc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/costcare.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costcare.cc\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/costcare.cc\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/logo.svg\",\"width\":1094,\"height\":441,\"caption\":\"Contract Care\"},\"image\":{\"@id\":\"https:\\\/\\\/costcare.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Klinikmanagement Archives - Contract Cost Care Ltd.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/","og_locale":"de_DE","og_type":"article","og_title":"Klinikmanagement Archives","og_url":"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/","og_site_name":"Contract Cost Care Ltd.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/","url":"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/","name":"Klinikmanagement Archives - Contract Cost Care Ltd.","isPartOf":{"@id":"https:\/\/costcare.cc\/#website"},"breadcrumb":{"@id":"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/costcare.cc\/de\/tag\/klinikmanagement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costcare.cc\/"},{"@type":"ListItem","position":2,"name":"Klinikmanagement"}]},{"@type":"WebSite","@id":"https:\/\/costcare.cc\/#website","url":"https:\/\/costcare.cc\/","name":"Contract Care","description":"maximum efficiency and cost saving for your medical treatment systems","publisher":{"@id":"https:\/\/costcare.cc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costcare.cc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/costcare.cc\/#organization","name":"Contract Care","url":"https:\/\/costcare.cc\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/costcare.cc\/#\/schema\/logo\/image\/","url":"https:\/\/costcare.cc\/wp-content\/uploads\/2024\/12\/logo.svg","contentUrl":"https:\/\/costcare.cc\/wp-content\/uploads\/2024\/12\/logo.svg","width":1094,"height":441,"caption":"Contract Care"},"image":{"@id":"https:\/\/costcare.cc\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/costcare.cc\/de\/wp-json\/wp\/v2\/tags\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costcare.cc\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/costcare.cc\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/costcare.cc\/de\/wp-json\/wp\/v2\/posts?tags=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}